{"id":86107,"date":"2020-12-23T18:09:15","date_gmt":"2020-12-23T17:09:15","guid":{"rendered":"https:\/\/www.freiburg-schwarzwald.de\/blog\/?page_id=86107"},"modified":"2026-08-06T09:04:27","modified_gmt":"2026-08-06T07:04:27","slug":"volkswirtschaft","status":"publish","type":"page","link":"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/","title":{"rendered":"Volkswirtschaft"},"content":{"rendered":"<p><a href=\"https:\/\/freiburg-schwarzwald.de\/blog\">Home<\/a>\u00a0&gt;<a title=\"Engagement\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/\">Engagement<\/a>\u00a0&gt;<a title=\"Zukunft\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/\">Zukunft<\/a>\u00a0&gt;<a title=\"Demokratie\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/\">Demokratie<\/a>\u00a0&gt;<a title=\"Global\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/\">Global<\/a>\u00a0&gt;<a title=\"Deutschland\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/\">Deutschland<\/a> &gt;Volkswirtschaft<\/p>\n<div id=\"attachment_85941\" style=\"width: 648px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2020\/12\/schauinsland-wetterbuchen202012-pan.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-85941\" class=\"size-full wp-image-85941\" src=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2020\/12\/schauinsland-wetterbuchen202012-pan.jpg\" alt=\"\" width=\"638\" height=\"298\" srcset=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2020\/12\/schauinsland-wetterbuchen202012-pan.jpg 638w, https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2020\/12\/schauinsland-wetterbuchen202012-pan-180x84.jpg 180w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/a><p id=\"caption-attachment-85941\" class=\"wp-caption-text\">Wetterbuchen vom Rosshang in Hofsgrund am Schauinsland am 10.12.2020: Schnee &#8211; Buchen &#8211; Nebel &#8211; Sonne<\/p><\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><em>Listenauswahl eines Beitrags (Artikel\/Datum, Seite\/Inhalt):\u00a0<span style=\"text-decoration: underline;\">Klicken<\/span>\u00a0oder scrollen<\/em><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/nullsumme-zero-sum-mindset\/\">Nullsumme \u2013 Zero Sum Mindset<\/a>\u00a0(5.8.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie-knowhow-germany\/\">Energie + KnowHow = Made in Germany<\/a>\u00a0(31.5.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/sozialismus\/sozialismus-gruene\/\">Konrad Adam: Die Sozialkapitalisten<\/a> (27.5.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/eigentumsoekonomik-vs-absturz\/\">Eigentums\u00f6konomik vs Absturz<\/a>\u00a0(5.5.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/absturz\/\">Absturz \u2013 So retten wir Deutschland -von Daniel Stelter<\/a>\u00a0(24.4.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/mittelstandsvernichtung\/\">Eberhard Hamer: Politische Mittelstandsvernichtung<\/a>\u00a0(11.4.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/reichtum\/\">IW-Studie: Leistungstr\u00e4ger sind die fiskalischen Packesel der Republik<\/a>\u00a0(2.2.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/faule-deutsche-auch-dumm\/\">Faule Deutsche \u2013 auch dumm?<\/a>\u00a0(31.1.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/china-russland-usa-eu-und-d\/\">China Russland USA EU und D<\/a>\u00a0(8.1.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/usa\/usa-trump\/\">Prof Moosdorf auf X \u00fcber Trump\u2019s positive USA-Bilanz<\/a>\u00a0(20.1.2026)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/niedergang-oekonomie-freiheit\/\">Niedergang: \u00d6konomie, Freiheit<\/a>\u00a0(1.11.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/zusammenbruch\/\">Niedergang seit 1990 \u2013 in Richtung erneutem Zusammenbruch?<\/a>\u00a0 (4.10.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/krieg\/kriegswirtschaft\/\">Kriegswirtschaft soll L\u00fccke schlie\u00dfen<\/a>\u00a0(18.8.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/niedergang-wirtschaft-kritik\/\">Niedergang: Wirtschaft, Kritik<\/a>\u00a0(18.8.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/oekonomie\/\">Warum zerbricht dieses Land? Der Kampf gegen die Realit\u00e4t<\/a>\u00a0(17.8.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/vdl-verkauft-die-eu-an-die-usa\/\">vdL verkauft die EU an die USA<\/a>\u00a0(29.7.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/schrumpfung\/\">Deutsche Wirtschaft in der gr\u00f6\u00dften Krise der Geschichte der Bundesrepublik<\/a> (24.4.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/globalisierung\/blackrock\/\">BlackRocks Billionenmacht: Finanzgiganten auf dem Vormarsch<\/a>\u00a0(23.4.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/zollpolitik\/\">Dr. Trumps Diagnose: Z\u00f6lle sind die Medizin f\u00fcr einen kranken Status Quo<\/a> (4.4.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/spareninvestition-vs-konsum\/\">Sparen=Investition vs Konsum<\/a>\u00a0(15.3.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/abwaerts-immer-aufwaerts-nimmer\/\">Abw\u00e4rts immer, aufw\u00e4rts nimmer<\/a> (2.3.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/bip-42-vs-staat-2-billionen-euro\/\">BIP 4,2 vs Staat 2 Billionen Euro<\/a> (2.1.2025)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/sinn\/\">Hans-Werner Sinn rechnet mit Scholz, Merkel und EU ab<\/a>\u00a0(2.12.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/mittelstand-proteste\/\">WVIB-Pr\u00e4sident Bert Sutter: \u201eWir sind zu teuer, zu b\u00fcrokratisch, zu selbstverliebt\u201c<\/a>\u00a0(21.11.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/marktwirtschaft\/privatisierung\/\">Hamer: Privatwirtschaft rentabler als Staatswirtschaft<\/a>\u00a0(31.10.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/consent-of-the-governed\/vertrauen\/\">Vertrauensverlust \u2013 der Anfang vom Ende<\/a>\u00a0(3.10.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/prof-sinn-oekonomie-ruiniert\/\">Prof Sinn: \u00d6konomie ruiniert<\/a>\u00a0(3.9.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/germany\/\">Prof Eberhard Hamer: Germany ist nicht mehr Deutschland<\/a> (26.7.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/globalisierung\/world-ranking\/\">World-Competitiveness Ranking: D auf Platz 24 von 67 abgerutscht<\/a>\u00a0(15.7.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/klimarettung\/\">Klimafreundlich verelendet: Belege f\u00fcr eine absichtliche Zerst\u00f6rung<\/a>\u00a0(15.7.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/deutsche-interessen\/\">S\u00f6llner: Deutscher Moralismus contra eigene Interessen<\/a>\u00a0(21.6.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/insolvenz\/\">Deindustrialisierung: Die Zahl der Firmenaufl\u00f6sungen steigt<\/a>\u00a0(21.6.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/boerse-ceo-d-als-ramschladen\/\">B\u00f6rse-CEO: D als Ramschladen<\/a>\u00a0(9.6.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/iw-studie-bildung-migration\/\">IW-Studie: Bildung \u2013 Migration<\/a>\u00a0(1.6.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wann-kommt-der-aufschwung\/\">Wann kommt der Aufschwung?<\/a> (7.5.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/argentinien\/\">Javier Milei: 100 Tage libert\u00e4re Revolution<\/a>\u00a0(8.4.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/bildung\/infantil\/\">Habeck: \u201eDer Wirtschaft geht es gut, aber die Zahlen sind schlecht\u201d<\/a> (24.2.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staatsapparat\/\">Die Ampel, nicht die AfD, besch\u00e4digt den Wirtschaftsstandort Deutschland<\/a>\u00a0(16.2.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/schrumpfung\/\">Deutschlands Wirtschaft schrumpft<\/a>\u00a0(18.1.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/natur\/klima\/transformation\/\">Agora macht weiter \u2013 CO2-R\u00fcckgang aber nur wegen Rezession<\/a> (12.1.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/migration-zerstoert-sozialsystem\/\">Migration zerst\u00f6rt Sozialsystem<\/a> (13.1.2024)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/wirtschaftswachstum\/\">Deutschland \u2013 erneut der kranke Mann Europas<\/a> (27.11.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staat\/staatshaushalt\/\">Thilo Sarrazin: Sozialausgaben erdrosseln Staatsfinanzen<\/a>\u00a0(14.9.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/prof-sinn-erdoel-gas-verbote\/\">Prof Sinn: Erd\u00f6l-\/Gas-Verbote<\/a>\u00a0(1.8.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/planwirtschaft\/\">Die Wende von der Marktwirtschaft in die Wirtschaftsdiktatur<\/a>\u00a0(16.6.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie\/akw\/atomausstieg\/\">Habeck &amp; Lang zerst\u00f6ren Dinge, die heil sind: Atomkraftwerke und unsere Wirtschaft<\/a>\u00a0(19.4.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/eu-planwirtschaft\/\">EU: Von der Investitionsunion zur Umverteilungsagentur<\/a> (14.4.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/feindschaft-zu-china-nein\/\">Feindschaft zu China? Nein!<\/a>\u00a0(15.4.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/die-obrigkeit-der-scharlatane\/\">Die Obrigkeit der Scharlatane<\/a>\u00a0(23.3.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/mittelstandsunternehmen\/\">Der Staat wirbt dem Mittelstand das Personal ab<\/a>\u00a0(3.3.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/alarm-basf-geht-nach-china\/\">Alarm: BASF geht nach China<\/a>\u00a0(27.2.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/wirtschaftswachstum\/\">Worin Wachstumskritiker grunds\u00e4tzlich irren<\/a> (17.2.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/produktion\/\">Autozulieferer halten Deutschland nicht mehr f\u00fcr wettbewerbsf\u00e4hig<\/a>\u00a0(15.2.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/ukraine\/ukrainekrieg\/\">Den Kollaps verhindern: Durch Kriegswirtschaft oder eine \u00d6ko-Diktatur?<\/a> (11.2.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/ohne-mittelstand-kein-wohlstand\/\">Ohne Mittelstand kein Wohlstand<\/a>\u00a0(5.2.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/gruene-oekonomie\/\">Gr\u00fcne \u00d6konomie- Wieder ein Paradies?<\/a>\u00a0(5.1.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/ampel\/\">Ampel: Politik der Verarmung<\/a>\u00a0(1.1.2023)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/weihnachtsvorlesung-prof-sinn\/\">Weihnachtsvorlesung: Prof Sinn<\/a>\u00a0(16.12.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/niedergang\/\">Weltweit viertgr\u00f6\u00dfte Volkswirtschaft im Niedergang \u2013 selbstgemach<\/a>t (5.12.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staat\/schuldenpolitik\/\">Schuldenpolitik von Deutschland seit 1960<\/a>\u00a0(25.11.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/deindustrialisierung-verarmung\/\">Deindustrialisierung: Verarmung<\/a>\u00a0(27.10.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/mittelstand-wirtschaft-bergab\/\">Mittelstand \u2013 Wirtschaft bergab<\/a>\u00a0(15.10.2022)<\/li>\n<li>Modern-Money-Theory beschleunigt denselbstverschuldeten Zusammenbruch (30.9.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/deutschland-ist-ein-reiches-land\/\">Deutschland ist ein reiches Land<\/a>\u00a0(28.9.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie\/energiekosten\/\">Eberhard Hamer: Energiekosten zur Verarmung<\/a>\u00a0(21.9.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wohlstand-commons-sinken\/\">Wohlstand + Commons sinken<\/a>\u00a0(24.9.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/eu-plan-statt-marktwirtschaft\/\">EU: Plan- statt Marktwirtschaft<\/a>\u00a0(17.9.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/wohlstandsverlust\/\">Eberhard Hamer: Selbstgemachter Absturz<\/a>\u00a0(19.8.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/unternehmer\/\">Mittelstands-\u00d6konom Prof. Eberhard Hamer wird 90 Jahre alt<\/a>\u00a0(15.8.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/\">Verbandschef BVMW: Im Mittelstand herrscht blanke Existenzangst<\/a>\u00a0(15.8.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/konjunktur\/\">Nicht nur Rezession, sondern Depression droht<\/a>\u00a0(27.7.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/antirealistischer-schutzwall\/\">Antirealistischer Schutzwall<\/a>\u00a0(31.7.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/schweiz\/schweiz-wirtschaft\/\">33 Franken f\u00fcr eine Pizza Margherita \u2013 warum die Schweiz so teuer ist<\/a> (20.7.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/fuer-diesen-staat-arbeiten-nein\/\">F\u00fcr diesen Staat arbeiten? Nein!<\/a>\u00a0(18.7.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/sanktionen\/\">Antja Vollmer: Sanktionen als \u201eWirtschaftspolitik der verbrannten Erde\u201c gescheitert<\/a> (14.7.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie\/gas\/nordstream2\/\">Lafontaine: Nordstream 2 \u00f6ffnen<\/a> (7.7.2022)<\/li>\n<li>Weltweites Bruttoinlandsprodukt 2021 nach L\u00e4ndern, in Billionen US-Dollar (21.5.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/100-jahre-rapallo-vertrag-d-ru\/\">100 Jahre Rapallo-Vertrag Deutschland \u2013 Russland<\/a>\u00a0(20.5.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/deutschland-russland\/\">K\u00fcnstle\u2019s Sicht: Deutsch-russische Beziehungen im Zeitraffer<\/a>\u00a0(10.5.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staatsquote\/\">Staatsquote steigt \u2013 Wirtschaft geht bergab<\/a>\u00a0(19.4.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/sanktionen\/\">Energie-Sanktionen: Europa s\u00e4gt am eigenen Ast<\/a>\u00a0(8.4.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/sechs-lng-tankschiffe-pro-tag\/\">Sechs LNG-Tankschiffe pro Tag?<\/a>\u00a0(23.3.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/wohlstandsverlust\/\">6-Punkte-Realpolitik statt gr\u00fcnsozialistische Illusionen<\/a>\u00a0(18.3.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/wohlstandsverlust\/\">Deutschlands wirtschaftlicher Niedergang<\/a>\u00a0(6.3.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/dienste\/banken\/inflation\/\">Die B\u00e4ndigung der Geldflut<\/a>\u00a0(13.1.2022)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wehret-den-anfaengen-zu-spaet\/\">Wehret den Anf\u00e4ngen \u2013 zu sp\u00e4t?<\/a>\u00a0(30.7.2021)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/wohlstandsverlust\/\">Von der Aufbau- zur Zerst\u00f6rergeneration unserer Wirtschaft<\/a>\u00a0(16.7.2021)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/gesund\/corona-virus\/lockdown\/\">Neue Ioannidis-Studie erweist Lockdowns als wirkungslos<\/a> (12.1.2021)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/lebensschutz-statt-lockdowns\/\">Lebensschutz statt Lockdowns<\/a>\u00a0(7.1.2021)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/steuerzahler-steuergeldbezieher\/\">Nur 15 Mio Steuergeldzahler und viel mehr Steuergeldbezieher<\/a>\u00a0(3.1.2021)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/gesund\/corona-virus\/weihnachten-corona\/\">Keine epidemische Lage nationaler Tragweite?<\/a>\u00a0(30.12.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/lockdown-auch-fuer-das-klima\/\">Lockdown auch f\u00fcr das Klima?<\/a>\u00a0(28.12.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/rezession\/corona-sozialismus\/\">Die 6 schlimmsten Lockdown-Kollateralsch\u00e4den<\/a>\u00a0(27.12.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/\">Corona: Datenschutz\/offene Grenzen (D) \u2013 Wirtschaft\/Leben (Asien)<\/a>\u00a0(24.12.2020)<\/li>\n<li>\u00dcberschuldung: Inflation, W\u00e4hrungsschnitt oder Bankrott (23.12.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/gesund\/corona-virus\/lockdown\/\">Joachim Starbatty: Wer soll das alles bezahlen<\/a>\u00a0(13.11.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/\">Staatsverschuldung in Deutschland 2020 \u00fcber 2,1 Billionen Euro<\/a> (19.10.2020)<\/li>\n<li><a title=\"2020 Jahr der EU-Transferunion\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/2020-jahr-der-eu-transferunion\/\">2020 ist das Jahr der EU-Transferunion<\/a>\u00a0(18.9.2020)<\/li>\n<li><a title=\"Wahrheit \u2013 gef\u00fchlte Wahrheit\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wahrheit-gefuehlte-wahrheit\/\">Wahrheit und Gef\u00fchlte Wahrheit<\/a>\u00a0(28.8.2020)<\/li>\n<li><a title=\"EU-Transferunion\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/eu-transferunion\/\">Sinn: Der EU-Wiederaufbaufonds f\u00fchrt zum Verlust der Wettbewerbsf\u00e4higkeit<\/a>\u00a0(23.8.2020)<\/li>\n<li><a title=\"Target-Saldo EU: 1 Billion Euro\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/target-saldo-eu-1-billion-euro\/\">Target-Saldo der deutschen Bundesbank \u00fcberschreitet eine Billion Euro<\/a>\u00a0(8.8.2020)<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/\">Johannes Eisleben: Gipfel des EU-Schuldenwahns<\/a> (24.7.2020)<\/li>\n<\/ul>\n<ul>\n<li><a title=\"750 Mrd neu EU-Schuldenunion\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/750-mrd-neu-eu-schuldenunion\/\">750 Euro neue Corona-Kredite \u2013 EU-Schuldenunion<\/a>\u00a0(23.7.2020)<\/li>\n<li><a title=\"750 Mrd neu EU-Schuldenunion\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/750-mrd-neu-eu-schuldenunion\/\">Gunnar Heinsohn: Der Elefant im Br\u00fcsseler Verhandlungsraum \u2013 Spanien und Italien<\/a>\u00a0(22.7.2020)<\/li>\n<li><a title=\"BVerfG: D-Recht vor EU-Recht\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/bverfg-d-recht-vor-eu-recht\/\">BVerfG-Urteil\u00a0verbietet EZB-Anleihek\u00e4ufe: Deutsches Recht vor EU-Recht<\/a>\u00a0(7.5.2020)<\/li>\n<li><a title=\"Deutschland2020\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/deutschland2020\/\">Markus Krall und Max Otte im Gespr\u00e4ch: Was passiert mit unserem Geld?<\/a>\u00a0(22.3.2020)<\/li>\n<li><a title=\"Die EU ist lieb und wird teurer\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/die-eu-ist-lieb-und-wird-teurer\/\">Die EU ist uns lieb und wird uns teurer<\/a>\u00a0(4.2.2020)<\/li>\n<li><a title=\"Finanzsystem\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/finanzsystem\/\">Sinn: EU-Fiskalunion (gemeinsame Kassen) nicht VOR der politischen Union<\/a>\u00a0(3.3.2016)<\/li>\n<li><a title=\"Dagegen\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/dagegen\/\">Wutb\u00fcrger \u2013 B\u00fcrger nehmen ihren Staat selbst in die Hand<\/a>\u00a0&gt;Dagegen (9.12.2013)<\/li>\n<li>VWL f\u00fcr Lieschen M\u00fcller &#8211; van Suntum&#8217;s Buch &#8222;Unsichtbare Hand&#8220; in der 4. Auflage (30.5.2011)<\/li>\n<li><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/55mrdeuro.htm\">55 Mrd Euro als Staatsschulden falsch verbucht \u2013 einfach so<\/a>\u00a0&gt;55MrdEuro<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/absturz\/\">Absturz<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/argentinien\/\">Argentinien<\/a><\/li>\n<li><a title=\"Bargeld\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/finanzsystem\/bargeld\/\">Bargeld<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/globalisierung\/blackrock\/\">Blackrock<\/a><\/li>\n<li><a title=\"Demokratie\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/\">Demokratie<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/deutschland-russland\/\">Deutschland-Russland<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie\/energiekosten\/\">Energiekosten<\/a><\/li>\n<li><a title=\"EU\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/\">EU<\/a><\/li>\n<li><a title=\"EU-Banken\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/eu-banken\/\">EU-Banken<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/gruene-oekonomie\/\">Gruene-Oekonomie<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/dienste\/banken\/inflation\/\">Inflation<\/a><\/li>\n<li><a title=\"IWF\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/finanzsystem\/iwf\/\">IWF<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/klimarettung\/\">Klimarettung<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/konjunktur\/\">Konjunktur<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/krieg\/kriegswirtschaft\/\">Kriegswirtschaft<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/industrie\/mittelstand\/mittelstandsvernichtung\/\">Mittelstandsvernichtung<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/niedergang\/\">Niedergang<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/energie\/gas\/nordstream2\/\">Nordstream2<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/oekonomie\/\">oekonomie<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/marktwirtschaft\/privatisierung\/\">privatisierung<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/sanktionen\/\">Sanktionen<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/schrumpfung\/\">Schrumpfung<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staat\/schuldenpolitik\/\">Schuldenpolitik<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/schweiz\/schweiz-wirtschaft\/\">Schweiz-Wirtschaf<\/a>t<\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/staat\/staatshaushalt\/\">Staatshaushalt<\/a><\/li>\n<li><a title=\"Steueroase\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/finanzsystem\/steueroase\/\">Steueroase<\/a><\/li>\n<li><a title=\"Target\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/target\/\">Target<\/a><\/li>\n<li><a title=\"EU-Transferunion\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/eu-transferunion\/\">Transfersystem in der EU<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/verarmung\/\">Verarmung<\/a><\/li>\n<li><a title=\"Vollgeld\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/vollgeld\/\">Vollgeld<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/\">Wirtschaft<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/wirtschaft\/wirtschaftswachstum\/\">Wirtschaftswachstum<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/selbsthilfe\/soziales\/wohlstandsverlust\/\">Wohlstandsverlust<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/globalisierung\/world-ranking\/\">World-Ranking<\/a><\/li>\n<li><a title=\"Zins\" href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/finanzsystem\/zins\/\">Zins<\/a><\/li>\n<li><a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/zollpolitik\/\">Zollpolitik<\/a><\/li>\n<\/ul>\n<p>.<\/p>\n<p><strong>Modern-Money-Theory beschleunigt den selbstverschuldeten Zusammenbruch<\/strong><br \/>\nWohlstand vorgaukeln<br \/>\nvon Thorsten Polleit<br \/>\nFrei nach Karl Marx und Friedrich Engel l\u00e4\u00dft sich sagen: \u201eEs geht ein Gespenst um auf der Welt, das Gespenst der \u2018Modernen Monet\u00e4ren Theorie\u2019 (MMT).\u201c In den Vereinigten Staaten ist die MMT \u2013 ihre prominentesten Bef\u00fcrworter sind die US-amerikanischen \u00d6konomen Warren Mosler und Stephanie A. Kelton \u2013 vor allem im linken Lager der Demokratischen Partei auf fruchtbaren Boden gefallen. In der volkswirtschaftlichen Diskussion ist sie hingegen weitgehend auf Kritik und auch auf Ablehnung gesto\u00dfen. Die Bef\u00fcrworter der MMT lassen sich dennoch nicht unterkriegen. Da volkswirtschaftliche Theorien, auch wenn sie falsch sind, wirkungsm\u00e4chtig werden und, wenn sie die Politik beeinflussen, gro\u00dfen Schaden anrichten k\u00f6nnen, ist es wichtig, sich eingehend mit ihnen auseinanderzusetzen.<\/p>\n<p>Fragen wir zun\u00e4chst: Was ist \u201emodern\u201c an der MMT? Nun, neu ist sie nicht. Die MMT ist vielmehr eklektisch, ihre Vertreter berufen sich auf viele bekannte Theorieelemente \u2013 wie auf Georg Friedrich Knapps \u201eStaatliche Theorie des Geldes\u201c und den damit verbundenen Chartalismus, (das hei\u00dft die Lehre, wonach das Geld eine Sch\u00f6pfung des Staates und seiner Rechtsordnung ist, und da\u00df der Geldwert ebenfalls staatlich bestimmt wird), sowie auf keynesianische und postkeynesianische Elemente und auch auf die Krisentheorie des \u00d6konomen Hyman P. Minsky. Das \u201emoderne\u201c an der MMT ist, diese und andere Theorieelemente miteinander zu verkn\u00fcpfen und sie als ein praktikables geld-, finanz- und wirtschaftspolitisches Konzept anzupreisen, mit dem sich angeblich dr\u00e4ngende Probleme der Zeit \u2013 wie zum Beispiel Wirtschaftskrisen, Un\u00adterbesch\u00e4ftigung und Staats\u00fcberschuldung \u2013 l\u00f6sen lassen.<\/p>\n<p>Konkret gesprochen besagt die MMT erstens: Der Staat soll sich fortan von seiner Zentralbank so viel Fiat-Geld sprichw\u00f6rtlich drucken lassen, wie er zur Bew\u00e4ltigung seiner Ausgaben braucht. Zweitens: Steuern werden nicht mehr zur Finanzierung des Staatshaushaltes erhoben, sondern nur noch um eine Nachfrage nach dem staatlichen Fiat-Geld sicherzustellen. Drittens: Der Staat betreibt eine kreditfinanzierte Nachfragepolitik, um die Volkswirtschaft auf Vollbesch\u00e4ftigung zu bringen. Viertens: Sollte es G\u00fcterpreisinflation geben, wird sie eingefangen, indem die Staatsdefizite entsprechend verringert und\/oder die Geldmenge in den H\u00e4nden der Privaten per Besteuerung reduziert werden. F\u00fcnftens: Der Staat kontrolliert mit seiner Defizitpolitik den Zins: Gibt er beispielsweise in Phasen der Konjunkturschw\u00e4che mehr aus, als er an Steuern einnimmt, beschafft er sich den Fehlbetrag durch neu geschaffenes Zentralbankgeld. Das zus\u00e4tzliche Zentralbankgeld im Interbankenmarkt steigt daraufhin an und senkt den Zins ab \u2013 und das wiederum bef\u00f6rdert Investitionen, Wachstum und Besch\u00e4ftigung. Sechstens: Indem der Staat das Ziel verfolgt, Vollbesch\u00e4ftigung zu sichern, stabilisiert er die Wirtschaft: Nimmt beispielsweise die Besch\u00e4ftigung ab, sorgt der Staat mit erh\u00f6hten Ausgaben \u2013 finanziert durch neu geschaffenes Geld \u2013 f\u00fcr eine erh\u00f6hte Nachfrage und mehr Arbeitsstellen; \u00fcberhitzt die Wirtschaft, verringert der Staat die Ausgaben und\/oder reduziert die Geldmenge durch Steuererh\u00f6hungen und legt sie still.<\/p>\n<p>Weniger bekannt scheint unter den Anh\u00e4ngern der MMT zu sein, da\u00df die grundlegende Idee der MMT geradewegs zu dem sozialistischen Denker Pierre-Joseph Proudhon (1809\u20131865) oder dem nationalsozialistischen Wirtschaftstheorie-Autodidakten Gottfried Feder (1883\u20131941) zur\u00fcckf\u00fchrt. Ihnen zufolge soll der Staat nicht nur die Hoheit \u00fcber die Geldproduktion haben, er soll vor allem auch ungehindert Zugang zu neuem Geld bekommen, das die Zentralbank ihm m\u00f6glichst zinslos bereitstellt. Da\u00df das aber auf ein geradezu gef\u00e4hrliches Staatsverst\u00e4ndnis hinausl\u00e4uft, sollte jedem klar sein, der den tieferen Sinn der Forderung \u201eNo taxation without representation\u201c versteht: Ihre Beachtung soll bekanntlich sicherstellen, da\u00df die Regierenden nicht ohne Zustimmung an Geld und Eigentum der Regierten kommen; und entsprechend ist die Mi\u00dfachtung dieser Forderung \u2013 wie sie die MMT einfordert \u2013 Ausdruck einer tyrannischen Gesinnung.<\/p>\n<p>Zudem ist der Gedanke, der Staat werde die G\u00fcterpreisinflation, verursacht durch die staatlich verursachte Geldmengenvermehrung, nicht aus dem Ruder laufen lassen, sie sogar bek\u00e4mpfen, sollte sie zu hoch ausfallen, v\u00f6llig realit\u00e4tsfremd: Es ist absehbar, da\u00df Regierungen sich, wenn sie ungehindert Zugang zur Notenpresse erhalten, immer mehr neues Geld beschaffen, es mit vollen H\u00e4nden ausgeben, um sich damit die Zustimmung der Regierten zu erkaufen. Gerade in modernen Demokratien sorgen Politiker sich um das Hier und Jetzt, scheren sich wenig um das Morgen. Hochinflation, wenn nicht gar Hyperinflation, werden daher die unausweichliche Begleiterscheinung der MMT sein.<\/p>\n<p>Absurd ist die Vorstellung, der Staat k\u00f6nnte mit seiner Ausgabenpolitik die Konjunktur oder gar die Volkswirtschaft gl\u00e4tten, sie stets auf Vollbesch\u00e4ftigungskurs halten. Das ist die urkeynesianische Idee der \u201eGlobalsteuerung\u201c, wie sie vom deutschen Volkswirt Karl Schiller (1911\u20131994), als er deutscher Wirtschafts- und Finanzminister war, von 1967 bis 1982 in die Tat umgesetzt wurde \u2013 und scheiterte. Der Staat, seine Politiker und B\u00fcrokraten, haben schlichtweg nicht das erforderliche Wissen, das Richtige zur richtigen Zeit zu tun. Zeitliche Verz\u00f6gerungen, die zwischen Politikma\u00dfnahmen und ihren Wirkungen auftreten, und die sich vorab nicht verl\u00e4\u00dflich vorhersehen lassen, machen es unm\u00f6glich, die gew\u00fcnschten Politikziele zu erreichen. Die MMT bietet keine L\u00f6sung f\u00fcr dieses Problem.<\/p>\n<p>Besonders problematisch ist, da\u00df die MMT dem heute weitestgehend akzeptierten Wissenschaftsverst\u00e4ndnis entstammt, nach dem die wissenschaftliche Methode der Naturwissenschaft \u2013 also Erkenntnisgewinnung durch Experimentieren \u2013 auf die \u00d6konomik zu \u00fcbertragen ist. Die Volkswirtschaft wird so de facto zum Versuchslabor deklariert. Gerade die \u00f6konomischen Theorien, die politisch Verhei\u00dfungsvolles versprechen \u2013 wie zum Beispiel \u201eDurch das Vermehren der Geldmenge steigt der Wohlstand\u201c oder \u201eNegativzinsen f\u00f6rdern Wachstum und Besch\u00e4ftigung\u201c oder \u201eSchulden sind kein Problem, der Staat soll Kredite aufnehmen\u201c \u2013, haben gute Chancen, politische Zustimmung zu finden, um sie tats\u00e4chlich in der Praxis auszuprobieren. Da\u00df die MMT Wissenschaftlichkeit beanspruchen kann, macht sie f\u00fcr Regierungen nur noch attraktiver.<\/p>\n<p>Es mag daher nicht \u00fcberraschen, da\u00df die MMT gerade im politischen Lager der Kollektivisten-Sozialisten-Marxisten auf gro\u00dfe Unterst\u00fctzung sto\u00dfen d\u00fcrfte. Die \u201ereine\u201c, nicht ideologisierte \u00f6konomische Lehre kann n\u00e4mlich absch\u00e4tzen, wohin die MMT letztlich f\u00fchrt: Sie bef\u00f6rdert das ungehemmte Vordringen des Staates in Wirtschaft und Gesellschaft zu Lasten der Freiheiten von B\u00fcrgern und Unternehmern \u2013 also genau das, was linken Eiferern \u00fcblicherweise vorschwebt. Der finanziell allm\u00e4chtige Staat wuchert aus, treibt B\u00fcrger und Unternehmer in seine Abh\u00e4ngigkeit \u2013 vor allem auch durch die N\u00f6te und Bed\u00fcrftigkeit, f\u00fcr die Hoch- oder gar Hyperinflation sorgen werden. So gesehen ist die MMT so etwas wie ein Trojanisches Pferd: eine Theorie, die, unter falscher Flagge in die Praxis umgesetzt, dem Staat zur Allmacht verhilft, B\u00fcrgern und Unternehmern monet\u00e4res Chaos beschert und dem Sozialismus den Boden bereitet.<\/p>\n<p>Mit einer gewissen Beklemmung mu\u00df man feststellen, da\u00df die MMT gewisserma\u00dfen das logische Ende vorwegnimmt, auf das die herrschende Wirtschafts- und Gesellschaftspolitik des Westens ohnehin zusteuert.<\/p>\n<p>Die Staatshaushalte sind seit Jahr und Tag chronisch defizit\u00e4r. Die Zentralbanken finanzieren die Staatsschulden mit k\u00fcnstlich gesenkten Zinsen und der Ausgabe von immer mehr neuem Geld. Weite Teile der Bev\u00f6lkerung sowie auch eine wachsende Zahl von Firmen sind in eine immer st\u00e4rkere Abh\u00e4ngigkeit von der staatlichen Ausgabe- und Versorgungspolitik geraten. Die \u201egr\u00fcne Politik\u201c, der gro\u00dfe geplante Umbau der Volkswirtschaften, bedient sich quasi bereits der MMT: Um die mit dem Ausstieg aus fossilen Brennstoffen verbundenen Kosten vor den Augen der \u00d6ffentlichkeit weitestgehend zu verbergen \u2013 wie vor allem die Zerschlagung der volkswirtschaftlichen Leistungsf\u00e4higkeit \u2013, bringen die Staaten gewaltige, mit neuen Schulden und neuem Geld finanzierte Unterst\u00fctzungspakete auf den Weg. Sie sollen die Konjunkturen vor dem Absturz bewahren, den Fortgang des Wohlstandes vorgaukeln.<\/p>\n<p>Mittlerweile tritt jedoch die dunkle Seite der wachsenden Staatsverschuldung, die von den Zentralbanken \u00e0 la MMT mit neu geschaffenem Geld bereitwillig finanziert wird, schonungslos zutage \u2013 und zwar in Form der Hochinflation. Sie zersetzt nicht nur die Kaufkraft des Geldes, die in Geld gehaltenen Ersparnisse und verarmt weite Teile der Bev\u00f6lkerung und setzt die wirtschaftliche Leistungsf\u00e4higkeit herab. Und wie schwierig es ist, eine erst einmal in Gang gekommene Hochinflation zu beenden, zeigen unmi\u00dfverst\u00e4ndlich die z\u00f6gerlichen Zinsanhebungen der Zentralbanken: Man scheut davor zur\u00fcck, die Kosten der Inflationsbeendigung \u2013 eine Stabilisierungsrezession \u2013 in Kauf zu nehmen und verh\u00e4rtet und verschlimmert damit das Inflationsproblem. Die MMT bietet da keine Politikalternative an, die hoffnungsvoll stimmen k\u00f6nnte.<\/p>\n<p><em>Prof. Dr. Thorsten Polleit, Jahrgang 1967, ist seit 2012 Chefvolkswirt der Degussa. Seit 2014 lehrt er als Honorarprofessor f\u00fcr Volkswirtschaftslehre an der Universit\u00e4t Bayreuth. Er ist Pr\u00e4sident des <a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/demokratie\/liberalismus\/libertarismus\/\">Ludwig-von-Mises-Instituts<\/a> Deutschland<\/em><br \/>\n&#8230; Alles vom 30.9.2022 von Thorsten Polleit bitte lesen in der JF40\/22, Seite 16<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Weltweites Bruttoinlandsprodukt 2021 nach L\u00e4ndern, in Billionen US-Dollar<\/strong><br \/>\n<a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2022\/06\/bip2021welt202205.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-101422\" src=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2022\/06\/bip2021welt202205.jpg\" alt=\"\" width=\"527\" height=\"622\" srcset=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2022\/06\/bip2021welt202205.jpg 527w, https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-content\/uploads\/2022\/06\/bip2021welt202205-153x180.jpg 153w\" sizes=\"auto, (max-width: 527px) 100vw, 527px\" \/><\/a><\/p>\n<p>&#8230; so klein ist Deutschland, das in seinem <a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/engagement\/zukunft\/groessenwahn\/\">Gr\u00f6\u00dfenwahn<\/a> die <a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/deutschland\/weltrettung\/\">Welt retten<\/a> will.<br \/>\n21.5.2022<br \/>\n.<\/p>\n<p><strong>\u00dcberschuldung: Inflation, W\u00e4hrungsschnitt oder Bankrott<\/strong><br \/>\nDer Staat wirft mit Milliarden um sich, die ihm gar nicht geh\u00f6ren<br \/>\n&#8211; Scholz pr\u00e4sentierte zu Weihnachten wieder \u201eSchein\u201c-Pakete besonderer Art<br \/>\n&#8211; Wie werden die Gl\u00e4ubiger des Auslands auf Totalverlust einmal regieren?<\/p>\n<p>Meine Mutter pflegte oft zu sagen, \u201eWenn Gott die Menschen strafen will, nimmt er den Herren den Verstand\u201c. Damit meinte sie Politiker, wenn sie unvern\u00fcnftig waren, und das Volk solche Entscheidungen auszubaden hatte. Heute w\u00fcrde sie nicht \u201eHerren\u201c sagen, sondern die da oben, weil sich in solche Kreise immer mehr Frauen gesellen. Unisono stellen sie Erfahrungen, Wissen, Logik und Vernunft auf den Kopf und f\u00e4lschen schlicht Fakten. Beispiele? Millionenfache Immigration mit milliardenschweren Folgen werden als \u201eBereicherung\u201c verf\u00e4lscht. Oder, das tausendfach sogar t\u00f6dliche Coronavirus wird oft menschenverachtend als \u201eChance\u201c bezeichnet, weil in Zeiten einer tats\u00e4chlichen Pandemie wie der Pest die eine oder andere Entdeckung gemacht wurde. Und heute muss das neue Virus herhalten, um die europ\u00e4ische und internationale Verwerfung des Finanzwesens mit neuen Billionen zu kaschieren. Womit ich beim Thema bin.<\/p>\n<p>Zuerst einige Grundlagen f\u00fcr die wenigen, die Volkswirtschaft nicht als Fach gew\u00e4hlt hatten. Diese Lehre vermittelte die einfache Formel S = I, d.h. die Summe der Ersparnisse (S) ist gleich der Summe aller Investitionen (I). Das war plausibel, denn alles, was von den geschaffenen Werten nicht verbraucht wurde, wird gespart und steht f\u00fcr Investitionen zur Verf\u00fcgung. In normalen Zeiten und nach Kriegen nahm die Wirtschaft das Geld der Banksparer und finanzierte damit ihre Investitionen zur Verbesserung der Produktivit\u00e4t. Und die Zinsen waren eine indirekte Beteiligung an den mit Investitionen erzielten Gewinnen. Heute braucht die Wirtschaft das Geld der Sparer nicht mehr, sie finanziert ihre Investitionen gr\u00f6\u00dftenteils selbst.<\/p>\n<p>Inzwischen \u00fcbertrifft der Staat den Geldhunger, den fr\u00fcher die Wirtschaft hatte. Als die Merkel-Regierung 2005 die Macht \u00fcbernahm, betrug die Schuldenquote gemessen am Inlandsprodukt BIP 66\u00a0Prozent. Nach f\u00fcnf Jahren war sie im Jahr 2010 auf 82\u00a0Prozent gestiegen. Die Mastrichtkriterien von 60\u00a0Prozent waren erstmals im letzten Jahr erf\u00fcllt. Jetzt liegt die Staatsverschuldung mit \u00fcber zwei Billionen Euro erneut \u00fcber 81\u00a0Prozent. Die Finanzsituation stand schon im Juni 2019 auf wackligen F\u00fc\u00dfen. Die Deutsche Bank wollte kritische Wert(los)papiere in eine neue Bad-Bank auslagern, in eine \u201einterne Abwicklungseinheit\u201c \u2013 ein Instrument der Schuldenkaschierung.<\/p>\n<p>In Europa sah es noch schlimmer aus. Hinl\u00e4nglich bekannt ist, dass die s\u00fcdl\u00e4ndischen \u201eOlivenstaaten\u201c weit \u00fcber ihre Verh\u00e4ltnisse gelebt haben und es anscheinend weiter tun. Aber unter dem Deckmantel der Target-II-Salden lassen sich Euro-Schulden einerseits und (vermeintliche) Guthaben leicht verstecken. So stehen andere Staaten bei unserer Bundesbank mit rund einer Billion Euro in der Kreide, ohne dass das anscheinend jemanden aufregt. Aber wie lange kann der Krug noch zum Brunnen gehen?<\/p>\n<p>Und dann kam das Jahr 2020 mit Corona. Gerade zur richtigen Zeit, weil sich das Finanzdesaster nicht viel l\u00e4nger h\u00e4tte kaschieren lassen? Einige Bereiche wurden nicht vom Virus, sondern durch staatliche Verordnungen heruntergefahren, die aus Gr\u00fcnden der Epidemie nicht h\u00e4tten geschlossen werden m\u00fcssen, z.B. Campingpl\u00e4tze, Ferienwohnungen, jetzt Gastst\u00e4tten und der Einzelhandel trotz ausreichenden Hygienekonzepten. Auch Urlaub machen in L\u00e4ndern mit weniger Infektionen stand auf dem Index. Die Folge: Die Menschen konnten kaum noch Geld ausgeben, die Girokonten f\u00fcllten sich, die Sparquote stieg zwangsl\u00e4ufig von 11\u00a0Prozent auf jetzt rund 20\u00a0Prozent. Das war kein \u201eAngstsparen\u201c sondern Kalk\u00fcl der Finanzstrategen. Das Geld, welches nicht mehr f\u00fcr das normale Leben ausgegeben werden kann, st\u00fcnde nun dem Zugriff des Fiskus zur Verf\u00fcgung.<\/p>\n<p>Weil aber n\u00e4chstes Jahr gew\u00e4hlt wird, verschieben sie das in die Zukunft und machen Schulden. Olaf Scholz, der schon als Erster B\u00fcrgermeister von Hamburg viel vom Schuldenmachen verstand, klotzt jetzt so richtig. Die indirekten Steuern gehen dieses Jahr zur\u00fcck, die direkten Steuern schlagen erst n\u00e4chstes Jahr so richtig zu Buche bzw. ins Konto. Mit Zustimmung des Bundestages wird alleine die Corona-Neuverschuldung 2020 von 90 auf 160\u00a0Mrd. EUR erh\u00f6ht und 2021 nochmal 180\u00a0Mrd. neue Schulden wegen Corona. Von h\u00f6heren Steuern zur Gegenfinanzierung der Einkommensausgleiche ist noch nicht die Rede. Aber kommt Zeit, kommt Steuer. Den Solidarit\u00e4tszuschlag f\u00fcr die Kompensierung der Deutschen Einheit gibt es noch heute.<\/p>\n<p>Europa \u00fcberbietet mit seinem neuen Haushalt alles bisher Dagewesene. Die EU finanziert sich nicht mehr allein \u00fcber Beitr\u00e4ge der Mitgliedsl\u00e4nder, die EU macht erstmals Schulden wie ihre Mitgliedsl\u00e4nder. Die Staats- und Regierungschefs stockten ihr \u201eKrisenprogramm\u201c vom M\u00e4rz Anfang Dezember auf 1,85\u00a0Billionen EUR auf. \u201eDeal!\u201c twitterte Ratspr\u00e4sident Charles Michel dazu, weshalb die Frage erlaubt sei, womit er fr\u00fcher sein Geld machte. Ob die deutsche Ratspr\u00e4sidentin Merkel auch etwas zu sagen hatte wie die Kommissionspr\u00e4sidentin v.d. Leyen? Und das immer noch auf Englisch, auch wenn Gro\u00dfbritannien den Hut nahm und ging?<\/p>\n<p>Erst bis 2058 sollen die aufgenommenen EU-Schulden zur\u00fcckgezahlt werden! Aber von wem? Jedenfalls erhielt dieses v.d.L.-EU-Programm der Kommissionspr\u00e4sidentin unter der Ratspr\u00e4sidentschaft von Angela Merkel (wer hat nun das Sagen, sie oder Charles Michel?) den ungesch\u00f6nt bitteren Titel \u201eNext Generation EU\u201c. Und Deutschlands n\u00e4chste und \u00fcbern\u00e4chste Generation wird davon die gr\u00f6\u00dfte Last zu tragen haben.<\/p>\n<p>Und die EZB entwickelt sich immer mehr zu einen \u201eSchwarzen Loch\u201c, das alles absorbiert, was in die Quere kommt, auch Schrott. Die EZB-Geldmenge betrug vor der Finanzkrise 2008 noch 0,9\u00a0Billionen Euro. Sie stieg jetzt unter seiner EZB-Pr\u00e4sidentin Christine Lagarde lt. Hans-Werner Sinn auf 4,6\u00a0Billionen und wird 2021 auf 6\u00a0Billionen Euro wachsen. Vielleicht deshalb hat George Soros die Idee, \u201edass sich die EU-Staaten mit ewigen Anleihen verschulden sollen, f\u00fcr die zwar Zinsen gezahlt werden, bei denen der Kredit aber nicht mehr zur\u00fcckgezahlt werden muss.\u201c Aber zur\u00fcck zum jetzigen Deutschland.<\/p>\n<p>Die hohe Verschuldung ist nicht alternativlos \u2013 so wenig wie es das Kanzleramt ist. Schulden sind gerechtfertigt f\u00fcr Investitionen. Je nachhaltiger Investitionen mit ihrer Nutzungsdauer sind, desto l\u00e4ngerfristig auch die Kredite. Aber die jetzt aufgelegten Programme dienen nur zum geringsten Teil Investitionen. Die nachgeholte Technik zur Digitalisierung ist in l\u00e4ngstens zehn Jahren veraltet und durch neue zu ersetzen, die Kreditlinien laufen aber \u00fcber 25\u00a0Jahre. Noch schlimmer, die Kredite werden nicht f\u00fcr Investitionen aufgenommen, sondern zum Ausgleich von politisch verursachten Einkommensausf\u00e4llen. Aber solche Einkommen sind weg, sie lassen sich volkswirtschaftlich nicht ausgleichen. Lock- und Shutdown bedeutet, null Schaffung von G\u00fctern und Diensten. Was passiert, wenn Geld gesch\u00f6pft wird, dem kein Inlandsprodukt gegen\u00fcbersteht? \u2026<\/p>\n<p>Das w\u00e4re die Alternative statt dem Schulden machen: Ich hatte es schon einmal vorgeschlagen. Diejenigen sollen jetzt f\u00fcr die Kosten aufkommen, denen die Ma\u00dfnahmen \u201ezu kurz, zu lasch, nicht hart genug\u201c sind. W\u00e4hrend in Deutschland 79\u00a0Prozent des Schadens mit Krediten, Garantien und B\u00fcrgschaften in die Zukunft verschoben wird, ist es in Holland nur die H\u00e4lfte. \u00d6sterreich verschiebt nur ein Viertel in die Zukunft und bittet aktuell jene zur Kasse, die nach Lockdown riefen und deren Konten wuchsen. Vorbildlich war Trump-USA; nur 15 Prozent der Kosten wurden auf den Sankt-Nimmerleins-Tag verschoben, fast alles \u201evon den Lebenden genommen\u201c oder an anderer Stelle eingespart. Vielleicht ist das ein Mitgrund, warum man ihn nicht weiter als Pr\u00e4sidenten haben m\u00f6chte. Bei uns zahlt sich Schuldenmachen politisch aus. Die Merkel-Mannschaft wird umso beliebter, je mehr Schulden sie macht.<\/p>\n<p>Was tun? Drei Szenarien gibt es zur Bew\u00e4ltigung der jetzt geschaffenen (nicht entstandenen) Krise.<br \/>\n1. Erstens eine wirkliche Inflation, nicht nur zwei Prozent Preissteigerung.<br \/>\n2. Oder irgendwann einen W\u00e4hrungsschnitt, wie es ihn nach den Kriegen gab.<br \/>\nAlso einen gro\u00dfen Reset der vermeintlichen Sparguthaben und der Staatsschulden.<br \/>\n3. Oder aber, Staaten leisten einen Offenbarungseid und r\u00e4umen ein, \u201ewir k\u00f6nnen<br \/>\neuch fr\u00fchere Kredite beim besten Willen nicht zur\u00fcckzahlen, irren ist politisch\u201c.<br \/>\nBetrug wird auch die n\u00e4chste Politikerklasse ihren fr\u00fcheren Artgenossen kaum vorwerfen. Eigentlich ist die Soros-Idee ehrlicher einzugestehen, dass die Darlehen an verschuldete Staaten nicht mehr zur\u00fcckgezahlt werden k\u00f6nnen, auch nicht mehr von unseren Regierungen.<\/p>\n<p>Das Problem wird aber f\u00fcr Deutschland gravierender und vielleicht sogar verh\u00e4ngnisvoll. Keiner wei\u00df warum, aber deutsche Anleihen werden unserem Finanzminister trotz der Nullverzinsung fast aus der Hand gerissen. Unser Staat erlebt eine Geldschwemme, aber die H\u00e4lfte der Deutschen Schulden werden vom Ausland gehalten. Dass die Anleger keine Zinsen erhalten, verschmerzen diese offensichtlich.<br \/>\nAber stellen wir uns vor, den Geldgebern des Auslands wird in 25 Jahren offenbart, es war edel von euch, uns damals aus der Patsche zu helfen, aber tut uns leid, wir k\u00f6nnen euer Geld nicht zur\u00fcckzahlen (leider taugen die <a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/global\/eu\/target\/\">Target-II-Salden<\/a> nicht zur Verrechnung). Stellen wir uns weiter vor, jene Ausl\u00e4nder haben eine bessere Armee als wir. In der Haut der Nachfolger einer AKK m\u00f6chte ich dann nicht stecken. Dann gibt es vermutlich kein weihnachtliches \u201eFriede auf Erden\u201c mehr. Bliebe stattdessen, sich nicht beim Ausland, sondern ausschlie\u00dflich bei der EZB zu verschulden, statt wie jetzt mit \u201enur\u201c 36 Prozent. Der Vorteil w\u00e4re: Die EZB k\u00f6nnte bei einer nicht m\u00f6glichen R\u00fcckzahlung schlecht mit Panzern \u201eargumentieren\u201c.<br \/>\n23.12.2020, Albrecht K\u00fcnstle, Herbolzheim, kuenstle.a \u00e4t gmx.e<\/p>\n<p>.<\/p>\n<p><strong>VWL f\u00fcr Lieschen M\u00fcller &#8211; van Suntum&#8217;s &#8222;Unsichtbare Hand&#8220; in 4. Auflage<\/strong><br \/>\n<strong>Mein Lieblingsbuch: van Suntum&#8217;s \u201cDie unsichtbare Hand\u201d<\/strong><\/p>\n<p>Medien versuchen aus Nachrichten Einzigartigkeiten zu schaffen. Das ist ihr Gesch\u00e4ft. Denn das Einzigartige findet Aufmerksamkeit. Was es (angeblich) noch nie gegeben hat, wird gelesen, geh\u00f6rt, geschaut.<br \/>\nVolkswirte sind so etwas wie die nat\u00fcrlichen Feinde der Medien, zumindest der Boulevard-Medien. \u201eDer Euro f\u00fchrt uns in die Katastrophe!\u201c Die Welt hat schon viele W\u00e4hrungsreformen erlebt \u2013 und \u00fcberlebt. \u201eDie aufstrebenden asiatischen Staaten greifen nach der \u00f6konomischen Weltherrschaft!\u201c Arbeitsteilung hilft am Ende allen. \u2013 Den apokalyptischen medialen Zukunftsszenarien stellt der besonnene Volkswirt die entspannte Analyse menschlicher Interaktionen gegen\u00fcber.<\/p>\n<p>Ulrich van Suntum ist so ein besonnener Volkswirt. Gerade ist in vierter Auflage sein Buch \u201eDie unsichtbare Hand \u2013 \u00f6konomisches Denken gestern und heute\u201c erschienen (29,95 Euro, Bestellung bei Amazon). Wie kein zweites deutschsprachiges Buch liefert es zu den allt\u00e4glichen Nachrichten fundierte \u00f6konomische Zusammenh\u00e4nge.<\/p>\n<p>Vernichtet der technische Fortschritt Arbeitspl\u00e4tze? Wie entsteht Inflation? Gehen uns bald die Rohstoffe aus? Auf alle relevanten \u00f6konomischen Debatten der vergangenen Jahrzehnte bietet \u201eDie unsichtbare Hand\u201c das \u00f6konomische R\u00fcstzeug \u2013 in Form von \u00f6konomischer Theorie, auch durch historische Vergleiche (Download Inhaltsverzeichnis).<\/p>\n<p>Auch die aktuelle Finanzkrise ist f\u00fcr den Professor am \u201eCentrum f\u00fcr angewandte Wirtschaftsforschung\u201c an der Universit\u00e4t M\u00fcnster keine wirkliche \u00dcberraschung: \u201eGro\u00dfe Finanzkrisen hat es auch schon fr\u00fcher gegeben, etwa den holl\u00e4ndischen Tulpenwahn im 17. Jahrhundert oder den Zusammenbruch der Papiergeldw\u00e4hrung in Frankreich ein knappes Jahrhundert sp\u00e4ter \u201c, schreibt van Suntum, \u201enur sind die Lehren daraus vielfach wieder vergessen worden.\u201c<\/p>\n<p>Es ist wohl Hans Besters, dem verstorbenen Professor f\u00fcr Volkswirtschaftslehre an der Ruhr-Universit\u00e4t Bochum, zu verdanken, dass es dieses Buch \u00fcberhaupt gibt. \u201eEr hat mich davor gewarnt\u201c, schreibt van Suntum, \u201eallein der Mathematik zu trauen, wenn es um \u00f6konomische Probleme geht.\u201c Letzten Endes habe Besters immer nur das gelten lassen, was man notfalls auch \u201eLieschen M\u00fcller\u201c habe klarmachen k\u00f6nnen.<\/p>\n<p>Das ist die St\u00e4rke von \u201eDie unsichtbare Hand\u201c: Es ist f\u00fcr Nicht-\u00d6konomen verst\u00e4ndlich und f\u00fcr \u00d6konomen dennoch erhellend.<\/p>\n<p>Diesem Buch sind viele Leser zu w\u00fcnschen. Doch dazu wird es vermutlich nicht kommen. Der Wissenschaftsverlag Springer gibt sich wenig bis keine M\u00fche, das Buch mit Hilfe der Optik f\u00fcr breitere Leserschichten attraktiv zu machen. Seit der ersten Auflage prangt eine langweilige Luftbildaufnahme Manhattens auf dem Cover. Das Foto soll wohl als Symbol f\u00fcr die Wirtschaft stehen. Doch van Suntums Buch ist so ziemlich genau das Gegenteil. Es geht ihm nicht um anonymes Wirtschaften. Zahlreiche \u00f6konomische Denker stellt van Suntum in seinem Buch vor, und ganz grunds\u00e4tzlich steht immer der Mensch im Mittelpunkt seiner \u00dcberlegungen.<br \/>\nEine gro\u00dfe Auflage ist also nicht zu erwarten. Es w\u00e4re schon viel gewonnen, wenn es in mancher Redaktion gelesen w\u00fcrde.<br \/>\n&#8230; Alles vom 30.5.2011 von Johannes Eber bitte lesen auf<br \/>\n<a href=\"https:\/\/pixeloekonom.de\/2011\/05\/30\/vwl-fur-lieschen-muller-van-suntums-unsichtbare-hand-in-vierter-auflage\/\">https:\/\/pixeloekonom.de\/2011\/05\/30\/vwl-fur-lieschen-muller-van-suntums-unsichtbare-hand-in-vierter-auflage\/<\/a><br \/>\n.<br \/>\n<em>Ulrich van Suntum: <\/em><br \/>\n<em>\u201eDie unsichtbare Hand \u2013 \u00f6konomisches Denken gestern und heute\u201c <\/em><br \/>\n<em>Gabler-Verlag, 316. S. , 2013, 5. Auflage<\/em><br \/>\n<em>29,95 Euro gebunden, 14,95 Euro als TB<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Home\u00a0&gt;Engagement\u00a0&gt;Zukunft\u00a0&gt;Demokratie\u00a0&gt;Global\u00a0&gt;Deutschland &gt;Volkswirtschaft &nbsp; Listenauswahl eines Beitrags (Artikel\/Datum, Seite\/Inhalt):\u00a0Klicken\u00a0oder scrollen Nullsumme \u2013 Zero Sum Mindset\u00a0(5.8.2026) Energie + KnowHow = Made in Germany\u00a0(31.5.2026) Konrad Adam: Die Sozialkapitalisten (27.5.2026) Eigentums\u00f6konomik vs Absturz\u00a0(5.5.2026) Absturz \u2013 So retten wir Deutschland -von Daniel Stelter\u00a0(24.4.2026) Eberhard Hamer: &hellip; <a href=\"https:\/\/www.freiburg-schwarzwald.de\/blog\/business\/volkswirtschaft\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":13,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-86107","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/pages\/86107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/comments?post=86107"}],"version-history":[{"count":6,"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/pages\/86107\/revisions"}],"predecessor-version":[{"id":152373,"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/pages\/86107\/revisions\/152373"}],"up":[{"embeddable":true,"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/pages\/13"}],"wp:attachment":[{"href":"https:\/\/www.freiburg-schwarzwald.de\/blog\/wp-json\/wp\/v2\/media?parent=86107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}